{"id":1,"name":"admin","url":"https:\/\/emmavivin.es","description":"","link":"https:\/\/emmavivin.es\/index.php\/author\/admin\/","slug":"admin","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0381f14e2e0e9e4bdbb5c17205c90224682d24f6be3b9ca262cd3441b3beeea7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0381f14e2e0e9e4bdbb5c17205c90224682d24f6be3b9ca262cd3441b3beeea7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0381f14e2e0e9e4bdbb5c17205c90224682d24f6be3b9ca262cd3441b3beeea7?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/emmavivin.es\/index.php\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emmavivin.es\/index.php\/wp-json\/wp\/v2\/users"}]}}